{"id":23019,"date":"2018-10-04T18:27:12","date_gmt":"2018-10-04T21:27:12","guid":{"rendered":"https:\/\/www.muniancud.cl\/inicio\/?p=22871"},"modified":"2018-10-31T10:19:06","modified_gmt":"2018-10-31T13:19:06","slug":"ancud-abre-primera-clinica-veterinaria-de-la-provincia","status":"publish","type":"post","link":"https:\/\/www.muniancud.cl\/portal\/ancud-abre-primera-clinica-veterinaria-de-la-provincia\/","title":{"rendered":"Ancud abre primera cl\u00ednica veterinaria de la provincia"},"content":{"rendered":"<div>\n<p>La iniciativa es pionera en materia de tenencia responsable de mascotas en el Archipi\u00e9lago.<\/p>\n<p>La inauguraci\u00f3n de la primera Cl\u00ednica Veterinaria Municipal de la provincia tuvo lugar recientemente en la comuna de Ancud, marcando un hito en la Isla Grande en cuanto a iniciativas que fomentan la tenencia responsable de mascotas.<\/p>\n<p>El objetivo de este nuevo espacio ser\u00e1 el de brindar atenci\u00f3n en cuanto a esterilizaciones e implantaciones de microchip a mascotas caninas y felinas de la comuna.<\/p>\n<p>La ceremonia de inauguraci\u00f3n fue encabezada por la primera autoridad comunal, alcalde Carlos G\u00f3mez Miranda, quien invit\u00f3 a los vecinos a hacer uso de esta cl\u00ednica veterinaria, \u201cla finalidad es entregar atenci\u00f3n a vecinos y vecinas de toda la comuna que requieran esterilizar mascotas o implantar el microchip, un equipo profesional los atender\u00e1\u201d, destac\u00f3 el edil, qui\u00e9n adem\u00e1s enfatiz\u00f3 en que no habr\u00e1 ning\u00fan costo para la comunidad ya que tanto la atenci\u00f3n como los insumos son completamente gratis, gracias a los recursos que el municipio gestion\u00f3 ante la Subsecretar\u00eda de Desarrollo Regional, SUBDERE.<\/p>\n<p>El m\u00e9dico veterinario a cargo del Plan de Tenencia Responsable de Mascotas de la comuna, Gerardo Morales, precis\u00f3 que esta iniciativa es una parte de un Plan comunal de tenencia responsable de mascotas y adelant\u00f3 que a futuro se espera poder ampliar la atenci\u00f3n a planes de vacunaci\u00f3n y desparasitaci\u00f3n gratuita de mascotas.<\/p>\n<p>Por su parte, la representante de la SUBDERE,\u00a0<span id=\"OBJ_PREFIX_DWT825_com_zimbra_date\" class=\"Object\"><span id=\"OBJ_PREFIX_DWT827_com_zimbra_date\" class=\"Object\">Mar<\/span><\/span>\u00eda Jos\u00e9 Gajardo, coordinadora programa tenencia responsable animales de compa\u00f1\u00eda de esta entidad, valor\u00f3 y destac\u00f3 la iniciativa del municipio de Ancud, ya que es la tercera en la regi\u00f3n, s\u00f3lo existen cl\u00ednicas veterinarias municipales en Puerto Montt y Osorno, adem\u00e1s de la reci\u00e9n inaugurada en nuestra comuna, adem\u00e1s invit\u00f3 al resto de las comunas de la regi\u00f3n a postular proyectos en esta misma l\u00ednea.<\/p>\n<p>Durante los primeros seis meses de funcionamiento de la Cl\u00ednica Veterinaria Municipal, se espera esterilizar a 1.200 mascotas e implantar 2.500 microchips. Tambi\u00e9n habr\u00e1 operativos de la cl\u00ednica en sectores rurales, seg\u00fan la demanda de los vecinos. Actualmente hay 600 mascotas inscritas esperando ser atendidas en la nueva cl\u00ednica veterinaria municipal, ubicada en Libertad 663, interior, detr\u00e1s de la Casa de la Cultura de Ancud.<\/p>\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La iniciativa es pionera en materia de tenencia responsable de mascotas en el Archipi\u00e9lago. La inauguraci\u00f3n de la primera Cl\u00ednica Veterinaria Municipal de la provincia tuvo lugar recientemente en la comuna de Ancud, marcando un hito en la Isla Grande en cuanto a iniciativas que fomentan la tenencia responsable de mascotas. El objetivo de este [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23026,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-23019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-de-prensa"],"_links":{"self":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/23019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/comments?post=23019"}],"version-history":[{"count":0,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/23019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media\/23026"}],"wp:attachment":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media?parent=23019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/categories?post=23019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/tags?post=23019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}