{"id":23025,"date":"2018-10-25T16:32:04","date_gmt":"2018-10-25T19:32:04","guid":{"rendered":"https:\/\/www.muniancud.cl\/inicio\/?p=22939"},"modified":"2018-11-10T10:37:45","modified_gmt":"2018-11-10T13:37:45","slug":"positivo-balance-preliminar-de-simulacro-de-tsunami-en-ancud","status":"publish","type":"post","link":"https:\/\/www.muniancud.cl\/portal\/positivo-balance-preliminar-de-simulacro-de-tsunami-en-ancud\/","title":{"rendered":"Positivo balance preliminar de simulacro de sismo y tsunami en Ancud"},"content":{"rendered":"<blockquote><p><em>Ejercicio preventivo tuvo lugar en las zonas costeras de la regi\u00f3n de Los Lagos.<\/em><\/p><\/blockquote>\n<p>Como estaba programado, esta jornada se realiz\u00f3 el simulacro regional de sismo y tsunami convocado por ONEMI Los Lagos, actividad preventiva en la que particip\u00f3 la comuna de Ancud. Una vez activada la alerta de sismo a trav\u00e9s de las sirenas de bomberos se inici\u00f3 el proceso de evacuaci\u00f3n hacia zonas de seguridad. Una r\u00e1pida respuesta de cada integrante del Comit\u00e9 Operativo de Emergencias COE, permiti\u00f3 que este se constituyera a las 10:58 hrs, generando inmediatamente reportes de la coordinaci\u00f3n y las personas evacuadas tanto en el borde costero de en la zona urbana como en las localidades de Pu\u00f1ihuil y Villa Chacao.<\/p>\n<p>La primera autoridad comunal, Alcalde Carlos G\u00f3mez Miranda, indic\u00f3 que el \u00faltimo reporte generado por el COE se\u00f1alaba que<em> \u201cse desplazaron en terreno, trabajando y orientando a la comunidad 318 personas, con 37 veh\u00edculos de las distintas instituciones participantes\u201d<\/em>, adem\u00e1s el edil detall\u00f3 que en total hubo 16 puntos de encuentro habilitados, diez de ellos en zona urbana, tres en Pu\u00f1ihuil y tres en Villa Chacao. El n\u00famero total de personas que participaron de este simulacro asciende a 11.748, de las cuales 4 mil fueron evacuadas ya que se encontraban en zona de riesgo de inundaci\u00f3n.<\/p>\n<p>El alcalde ancuditano aprovech\u00f3 la ocasi\u00f3n para <em>\u201cagradecer a la comunidad y a las instituciones por la participaci\u00f3n, orden y seriedad que le han puesto a este ejercicio y principalmente agradecer la colaboraci\u00f3n de todas las instituciones para llevar adelante este simulacro con \u00e9xito\u201d<\/em>, destac\u00f3 el edil, quien puntualiz\u00f3 que en los pr\u00f3ximos d\u00edas el COE se reunir\u00e1 para evaluar con mayor detalle este evento y afinar posibles falencias ante una emergencia real.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ejercicio preventivo tuvo lugar en las zonas costeras de la regi\u00f3n de Los Lagos. Como estaba programado, esta jornada se realiz\u00f3 el simulacro regional de sismo y tsunami convocado por ONEMI Los Lagos, actividad preventiva en la que particip\u00f3 la comuna de Ancud. Una vez activada la alerta de sismo a trav\u00e9s de las sirenas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":23089,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-23025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-de-prensa"],"_links":{"self":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/23025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/comments?post=23025"}],"version-history":[{"count":0,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/23025\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media\/23089"}],"wp:attachment":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media?parent=23025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/categories?post=23025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/tags?post=23025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}