{"id":26476,"date":"2020-01-10T08:50:57","date_gmt":"2020-01-10T11:50:57","guid":{"rendered":"https:\/\/www.muniancud.cl\/portal\/?p=26476"},"modified":"2020-01-10T08:51:12","modified_gmt":"2020-01-10T11:51:12","slug":"servicio-de-recoleccion-de-residuos-solidos-domiciliarios-10-de-enero","status":"publish","type":"post","link":"https:\/\/www.muniancud.cl\/portal\/servicio-de-recoleccion-de-residuos-solidos-domiciliarios-10-de-enero\/","title":{"rendered":"Servicio de recolecci\u00f3n de Residuos S\u00f3lidos Domiciliarios 10 de enero"},"content":{"rendered":"<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"bnkua-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"bnkua-0-0\"><span data-offset-key=\"bnkua-0-0\">La Ilustre Municipalidad de Ancud, reitera a la comunidad que a\u00fan se mantiene la contingencia que genera la extensi\u00f3n de la alerta sanitaria y que impide la recolecci\u00f3n de Residuos S\u00f3lidos Domiciliarios en nuestra comuna.\u00a0<\/span><\/div>\n<div class=\"_1mf _1mj\" data-offset-key=\"bnkua-0-0\">El motivo es la imposibilidad de realizar la disposici\u00f3n en un sitio autorizado por la Secretar\u00eda Regional Ministerial de Salud, mediante Resoluci\u00f3n Sanitaria.<\/div>\n<div class=\"_1mf _1mj\" data-offset-key=\"bnkua-0-0\">Sin embargo, se continua trabajando e insistiendo ante la las autoridades del gobierno regional y provincial\u00a0para que otorguen una soluci\u00f3n real, aunque transitoria, para los casi 39 mil habitantes de Ancud.<\/div>\n<\/div>\n<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"4u823-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"4u823-0-0\"><\/div>\n<div class=\"_1mf _1mj\" data-offset-key=\"4u823-0-0\">Mientras, se reitera el llamado a las vecinas y vecinos, a no sacar nuevamente los desechos a la v\u00eda p\u00fablica, por favor, contenerlos de la mejor forma posible en los domicilios. Ya sea en contenedores o bolsas bien cerradas, hasta que esta situaci\u00f3n sea superada.<\/div>\n<div class=\"_1mf _1mj\" data-offset-key=\"4u823-0-0\"><\/div>\n<\/div>\n<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"5402q-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"5402q-0-0\"><span data-offset-key=\"5402q-0-0\">Evite generar micro basurales.<\/span><\/div>\n<div class=\"_1mf _1mj\" data-offset-key=\"5402q-0-0\">Es muy importante no mezclar los desechos domiciliarios, para cuando puedan ser retirados de forma r\u00e1pida, en cuanto la autoridad regional logre determinar un lugar de disposici\u00f3n.<\/div>\n<div class=\"_1mf _1mj\" data-offset-key=\"5402q-0-0\"><\/div>\n<\/div>\n<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"amd10-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"amd10-0-0\">Sobre desechos org\u00e1nicos, visite www.muniancud.cl para inscribirse en el Programa de Compostaje Comunal y reducir a\u00fan m\u00e1s, los desechos del hogar.<\/div>\n<div class=\"_1mf _1mj\" data-offset-key=\"amd10-0-0\"><\/div>\n<div class=\"_1mf _1mj\" data-offset-key=\"amd10-0-0\">Se recomienda seguir la informaci\u00f3n de \u00faltimo minuto, sea a trav\u00e9s de medios de comunicaci\u00f3n, o en las RRSS y medios municipales.<\/div>\n<\/div>\n<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"8vq6v-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"8vq6v-0-0\"><\/div>\n<\/div>\n<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"8ks86-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"8ks86-0-0\"><span data-offset-key=\"8ks86-0-0\">Reiteramos.<\/span><\/div>\n<\/div>\n<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"64v3u-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"64v3u-0-0\"><span data-offset-key=\"64v3u-0-0\">No bote cart\u00f3n o papeles voluminosos.<\/span><\/div>\n<\/div>\n<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"4r2ih-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"4r2ih-0-0\"><span data-offset-key=\"4r2ih-0-0\">No deseche escombros o restos de podas en el servicio de recolecci\u00f3n de desechos domiciliarios.<\/span><\/div>\n<div class=\"_1mf _1mj\" data-offset-key=\"4r2ih-0-0\"><\/div>\n<div class=\"_1mf _1mj\" data-offset-key=\"4r2ih-0-0\">Coordine\u00a0operativos vecinales para el retiro de Podas, Chatarra, Chatarra Electr\u00f3nica o escombros con la Direcci\u00f3n de Aseo y Ornato de la Ilustre Municipalidad de Ancud.<\/div>\n<\/div>\n<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"36k80-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"36k80-0-0\"><span data-offset-key=\"36k80-0-0\">Tel\u00e9fono: 65-2487669<\/span><\/div>\n<\/div>\n<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"1ns00-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"1ns00-0-0\"><span data-offset-key=\"1ns00-0-0\">Consultas directas al WhatsApp +56967604504<\/span><\/div>\n<\/div>\n<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"cgru9-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"cgru9-0-0\"><span data-offset-key=\"cgru9-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"54sbu-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"54sbu-0-0\"><span data-offset-key=\"54sbu-0-0\">Mapa Online para Cuadrantes y puntos de acopio y reciclaje.<\/span><\/div>\n<\/div>\n<div class=\"\" style=\"color: #222222;font-family: Verdana, Geneva, sans-serif;font-size: 15px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;background-color: #ffffff\" data-block=\"true\" data-editor=\"9nrrs\" data-offset-key=\"mceq-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"mceq-0-0\"><span data-offset-key=\"mceq-0-0\">https:\/\/www.google.com\/maps\/d\/u\/0\/viewer?hl=es&amp;mid=1HxEPnEKA74EbzjFELx87zTJ1m4-Hto1s&amp;ll=-41.85819506190286%2C-73.78723943308495&amp;z=13&amp;fbclid=IwAR3dko0QVFOrRR-2dezqs_C1CzGyWsKl2udSTvur8gvnkhb-hZE4PjO8bGY<\/span><\/div>\n<div data-offset-key=\"mceq-0-0\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-25665 size-large\" src=\"https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2019\/09\/Manejo-RSD-Puntos-de-reciclaje-1-1024x618.jpg\" alt=\"\" width=\"696\" height=\"420\" srcset=\"https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2019\/09\/Manejo-RSD-Puntos-de-reciclaje-1-1024x618.jpg 1024w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2019\/09\/Manejo-RSD-Puntos-de-reciclaje-1-300x181.jpg 300w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2019\/09\/Manejo-RSD-Puntos-de-reciclaje-1-768x464.jpg 768w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2019\/09\/Manejo-RSD-Puntos-de-reciclaje-1-696x420.jpg 696w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2019\/09\/Manejo-RSD-Puntos-de-reciclaje-1-1068x645.jpg 1068w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2019\/09\/Manejo-RSD-Puntos-de-reciclaje-1-1920x1159.jpg 1920w\" sizes=\"auto, (max-width: 696px) 100vw, 696px\" \/><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Ilustre Municipalidad de Ancud, reitera a la comunidad que a\u00fan se mantiene la contingencia que genera la extensi\u00f3n de la alerta sanitaria y que impide la recolecci\u00f3n de Residuos S\u00f3lidos Domiciliarios en nuestra comuna.\u00a0 El motivo es la imposibilidad de realizar la disposici\u00f3n en un sitio autorizado por la Secretar\u00eda Regional Ministerial de Salud, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[37],"tags":[],"class_list":["post-26476","post","type-post","status-publish","format-standard","hentry","category-alerta-sanitaria"],"_links":{"self":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/26476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/comments?post=26476"}],"version-history":[{"count":2,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/26476\/revisions"}],"predecessor-version":[{"id":26478,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/26476\/revisions\/26478"}],"wp:attachment":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media?parent=26476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/categories?post=26476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/tags?post=26476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}