{"id":26489,"date":"2020-01-10T08:50:29","date_gmt":"2020-01-10T11:50:29","guid":{"rendered":"https:\/\/www.muniancud.cl\/portal\/?p=26489"},"modified":"2020-01-11T08:57:05","modified_gmt":"2020-01-11T11:57:05","slug":"municipio-de-ancud-invita-a-un-nutrido-fin-de-semana-costumbrista-cultural-y-turistico","status":"publish","type":"post","link":"https:\/\/www.muniancud.cl\/portal\/municipio-de-ancud-invita-a-un-nutrido-fin-de-semana-costumbrista-cultural-y-turistico\/","title":{"rendered":"Municipio de Ancud invita a un nutrido fin de semana costumbrista, cultural y tur\u00edstico"},"content":{"rendered":"<p>Con tres muestras costumbristas, la Ilustre Municipalidad de Ancud junto a la Corporaci\u00f3n Cultural y a las asociaciones costumbristas de Huelden, de las Dunas de Guab\u00fan y del sector rural de Pugue\u00f1\u00fan\u2013 Pihuio, invitan a la comunidad y turistas, a participar de las actividades t\u00edpicas de la cultura de Chilo\u00e9 a lo largo de este fin de semana en Ancud.<\/p>\n<p>La primera en iniciar las actividades, es la Muestra Costumbrista de Huelden, con la Fiesta de la Merluza. Desde este viernes 10, hasta este domingo de enero, los vecinos se suman a estas expresiones culturales en Ancud. Cada una despliega identidad cultural distinta. Huelden realiza el conocimiento cultural en la preparaci\u00f3n de la Merluza, Las Dunas de Guab\u00fan con la Trilla a brazos, destronques, \u201camansedumbre\u201d de animales, mientras Los Carboneros de Pugue\u00f1\u00fan \u2013 Pihuio, centran sus actividades en la extracci\u00f3n del carb\u00f3n, aserradura a mano y el troce de le\u00f1a. Siempre con la compa\u00f1\u00eda del folclore insular y la rica gastronom\u00eda de Chilo\u00e9 2020, con curantos, chochoca, asados y brebajes.<\/p>\n<p>Pedro C\u00e1rcamo presidente de la asociaci\u00f3n Dunas de Guab\u00fan, destaca las actividades e invita a participar de la muestra en su sector rural. \u201cInvito a todos los conocidos, amigos de distintas partes del de las zonas urbanas, porque Guab\u00fan est\u00e1 reconocido como una localidad que hace muchos eventos costumbristas. Para nosotros es un orgullo tener, la yunta de los chivos, las trillas, tenemos una yuntilla chiquitita que tira una casa\u201d, destac\u00f3 C\u00e1rcamo. Informando que, desde la costanera de Ancud, medios de transportes pueden acercar hasta la muestra en Guab\u00fan, que comienza a recibir visitantes desde las nueve de la ma\u00f1ana, hasta las veinte horas, de este s\u00e1bado y domingo.<\/p>\n<p>Desde Pugue\u00f1\u00fan \u2013 Pihuio, Pedro Ojeda integrante de la organizaci\u00f3n, invita a nombre de la comunidad y destaca el inter\u00e9s tur\u00edstico de este sector rural. \u201cInvitar. Invitar a la ciudadan\u00eda, a la comunidad, a los turistas. A la gente que visita Chilo\u00e9 a que se acerquen a este lugar para que disfrutar, de la gastronom\u00eda chilota, adem\u00e1s de lo cultural. Pero debemos decirle a la comunidad, que este sector est\u00e1 dentro de una ZOIT, del plan tur\u00edstico de nuestra comuna. lo que significa lugares de atracci\u00f3n, para la gente que nos visitan. No lo va a defraudar. Hartas actividades, buenas comidas, harto folclore. Le invita la gente del Pugue\u00f1\u00fan \u2013 Pihuio\u201d. Desde esta ma\u00f1ana hasta las ocho de la noche en ambos d\u00edas, esperan a los visitantes, en el marco de las Muestras Costumbristas 2020 en Ancud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con tres muestras costumbristas, la Ilustre Municipalidad de Ancud junto a la Corporaci\u00f3n Cultural y a las asociaciones costumbristas de Huelden, de las Dunas de Guab\u00fan y del sector rural de Pugue\u00f1\u00fan\u2013 Pihuio, invitan a la comunidad y turistas, a participar de las actividades t\u00edpicas de la cultura de Chilo\u00e9 a lo largo de este [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":26446,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,36],"tags":[],"class_list":["post-26489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-de-prensa","category-turismo"],"_links":{"self":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/26489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/comments?post=26489"}],"version-history":[{"count":1,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/26489\/revisions"}],"predecessor-version":[{"id":26490,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/26489\/revisions\/26490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media\/26446"}],"wp:attachment":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media?parent=26489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/categories?post=26489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/tags?post=26489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}