{"id":29078,"date":"2021-05-04T16:58:12","date_gmt":"2021-05-04T20:58:12","guid":{"rendered":"https:\/\/www.muniancud.cl\/portal\/?p=29078"},"modified":"2021-05-04T16:58:12","modified_gmt":"2021-05-04T20:58:12","slug":"municipio-de-ancud-reinicia-postulacion-a-composteras-urbanas","status":"publish","type":"post","link":"https:\/\/www.muniancud.cl\/portal\/municipio-de-ancud-reinicia-postulacion-a-composteras-urbanas\/","title":{"rendered":"Municipio de Ancud reinicia postulaci\u00f3n a composteras urbanas"},"content":{"rendered":"<p><strong><em>Programa municipal de la Direcci\u00f3n de Aseo y Ornato para reducir residuos org\u00e1nicos domiciliarios estar\u00e1 abierto hasta el 10 de mayo<\/em><\/strong><\/p>\n<p>La Direcci\u00f3n de Medio Ambiente, Aseo y Ornato de la Municipalidad de Ancud (DIMAO), desde el a\u00f1o pasado desarrolla un plan de compostaje que involucra a 640 familias que se encuentran diferenciando sus residuos org\u00e1nicos, aprovech\u00e1ndolos para el cultivo casero y reduciendo la cantidad de desechos que ingresan en el sitio de disposici\u00f3n final.<\/p>\n<p>En el marco de lo que el a\u00f1o 2020 fue \u201cAncud Composta\u201d, que durante este a\u00f1o 2021 se transforma en un programa mucho m\u00e1s integral dentro del municipio, y pasar a \u201cAncud Circular\u201d englobando todas las acciones en cuanto a reciclaje y en compostaje, y con ello se reabren las inscripciones para integrarse a este programa.<\/p>\n<p>El Encargado de la Dimao, Alfredo Caro, se\u00f1al\u00f3 que en el marco de este cambio de marca es que se le hace un nuevo llamado a postulaci\u00f3n para poder adquirir compostera en el sector urbano de la comuna. \u201cEstas postulaciones est\u00e1n abiertas hasta el d\u00eda 10 de mayo, por lo tanto invitamos a los vecinos a poder postular. Y quienes \u00a0no logren quedar dentro de los seleccionados igual invitarlos a estar atentos ya que en el segundo semestre nuevamente estaremos abriendo postulaciones para adquirir composturas para el sector urbano de la comuna\u201d.<\/p>\n<p>La raz\u00f3n esgrimida por Caro para que este proyecto se desarrolle dentro de los l\u00edmites urbanos se establece en la disponibilidad de espacios para poder realizar este tipo de segregaci\u00f3n de residuos. \u201cSon los lugares donde los patios son muchos m\u00e1s reducidos y donde ser\u00eda una problem\u00e1tica mayor poder manejar los residuos org\u00e1nicos si es que no se tuviese una compostera. a diferencia del sector rural, donde los patios son m\u00e1s amplios; hay permitido tener animales de granja a los cuales se le puede entregar este tipo de alimentaci\u00f3n, por lo tanto los residuos org\u00e1nicos no son un problema\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Agreg\u00f3 que tambi\u00e9n ser\u00e1 un punto importante el n\u00famero de integrantes de personas que viven en el hogar del postulante, considerando, eso si, que la implementaci\u00f3n del equipo de compostaje puede ser compartido con otro grupo familiar y as\u00ed llegar a m\u00e1s personas beneficiadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Programa municipal de la Direcci\u00f3n de Aseo y Ornato para reducir residuos org\u00e1nicos domiciliarios estar\u00e1 abierto hasta el 10 de mayo La Direcci\u00f3n de Medio Ambiente, Aseo y Ornato de la Municipalidad de Ancud (DIMAO), desde el a\u00f1o pasado desarrolla un plan de compostaje que involucra a 640 familias que se encuentran diferenciando sus residuos [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":29080,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,4],"tags":[],"class_list":["post-29078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medio-ambiente-aseo-y-ornato","category-sala-de-prensa"],"_links":{"self":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/29078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/comments?post=29078"}],"version-history":[{"count":1,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/29078\/revisions"}],"predecessor-version":[{"id":29082,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/29078\/revisions\/29082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media\/29080"}],"wp:attachment":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media?parent=29078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/categories?post=29078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/tags?post=29078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}