{"id":32259,"date":"2023-07-26T17:05:56","date_gmt":"2023-07-26T21:05:56","guid":{"rendered":"https:\/\/www.muniancud.cl\/portal\/?p=32259"},"modified":"2023-07-26T17:05:56","modified_gmt":"2023-07-26T21:05:56","slug":"ancud-contara-con-cuatro-nuevos-camiones-recolectores","status":"publish","type":"post","link":"https:\/\/www.muniancud.cl\/portal\/ancud-contara-con-cuatro-nuevos-camiones-recolectores\/","title":{"rendered":"Ancud contar\u00e1 con cuatro nuevos camiones recolectores"},"content":{"rendered":"<p><strong><em>Con una inversi\u00f3n de poco m\u00e1s de 705 millones, se sumar\u00e1n a los ya 5 existentes y posibilitar\u00e1n mejorar el servicio de recolecci\u00f3n en la ciudad y la zona rural<\/em><\/strong><\/p>\n<p><strong>\u00a0<\/strong>En votaci\u00f3n un\u00e1nime del Consejo Municipal de Ancud, fue aprobado el trato directo que posibilita la compra de cuatro nuevos camiones compactadores de basura para la comuna de Ancud. Este acto administrativo se pudo realizar, debido a que tres procesos previos de licitaci\u00f3n fueron declarados desiertos.<\/p>\n<p>As\u00ed, esta viene a ser una respuesta important\u00edsima a la urgencia que reviste el poder incrementar la actual flota de camiones que cubren el servicio de recolecci\u00f3n de residuos s\u00f3lidos domiciliarios en la zona urbana, como el sector rural de la comuna.<\/p>\n<p>Adem\u00e1s , es una herramienta que lograr\u00e1 bajar los costos que supone la contrataci\u00f3n de servicios complementarios de refuerzo a esta flota, como sucede actualmente, toda vez que Ancud es la \u00fanica comuna de la provincia en disponer sus residuos s\u00f3lidos domiciliarios en un sitio autorizado, distante a m\u00e1s de 600 km de la comuna, en Los \u00c1ngeles.<\/p>\n<p>La inversi\u00f3n, que bordea los $705 millones, se encuentra enmarcada al presupuesto asignado por el Gobierno Regional de Los Lagos, tras la aprobaci\u00f3n del proyecto que en su momento present\u00f3 el municipio ancuditano al ente gubernamental.<\/p>\n<p>Para Alfredo Caro, Director de Medio Ambiente, Aseo y Ornato del municipio local, este proyecto es importante para la comuna, que ya se hab\u00eda demorado bastante poder solicitado. Debido a tres licitaciones fallidas por parte de las empresas postulantes.<\/p>\n<p>\u201cHoy d\u00eda se realiza un trato directo, en marco de que han pasado m\u00e1s de seis meses que no podemos realizar esta licitaci\u00f3n, y con esto logramos comprar estos cuatro camiones, que vienen a reforzar la recolecci\u00f3n y tambi\u00e9n a ayudarnos a que no tengamos el problema de quedamos con basura pendiente por no tener el equipamiento necesario. Esperamos, ya dentro del pr\u00f3ximo mes, tener estos camiones en la comuna y avisaremos de la puesta en marcha de ellos\u201d, sostuvo el profesional.<\/p>\n<p>Una vez adquiridos los nuevos cuatro camiones Mercedes-Benz, la flota de veh\u00edculos de estas caracter\u00edsticas con las que contar\u00e1 el municipio ascender\u00e1 a 9 en total, con lo que se asegurar\u00e1 el cumplimiento del servicio de recolecci\u00f3n.<\/p>\n<p>\u201cEl principal cambio que vamos a ver reflejado es que lo m\u00e1s probable es que el sector rural vuelva a tener recolecci\u00f3n semanal y no cada 15 d\u00edas, quienes han sido los m\u00e1s postergados y quienes se han sacrificado por el resto de la comuna. Y tambi\u00e9n lo m\u00e1s probable es que repongamos la recolecci\u00f3n en el sector c\u00e9ntrico -que es donde se genera mayor cantidad de residuos, ya que ya que son lugares comunes-, a lunes mi\u00e9rcoles y viernes. Pero eso se va avisar en su momento, una vez que tengamos ac\u00e1 los camiones y podamos ir informando a cada una de las juntas de vecinos afectados con estos cambios\u201d, remarc\u00f3 Caro.<\/p>\n<p>Asimismo, el m\u00e9dico veterinario hizo un llamado a la comunidad a sacar los d\u00edas que corresponde y en contenedor los desechos domiciliarios, contribuyendo as\u00ed al trabajo e quienes deben recoger los residuos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una inversi\u00f3n de poco m\u00e1s de 705 millones, se sumar\u00e1n a los ya 5 existentes y posibilitar\u00e1n mejorar el servicio de recolecci\u00f3n en la ciudad y la zona rural \u00a0En votaci\u00f3n un\u00e1nime del Consejo Municipal de Ancud, fue aprobado el trato directo que posibilita la compra de cuatro nuevos camiones compactadores de basura para [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":32164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,4],"tags":[],"class_list":["post-32259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medio-ambiente-aseo-y-ornato","category-sala-de-prensa"],"_links":{"self":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/32259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/comments?post=32259"}],"version-history":[{"count":1,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/32259\/revisions"}],"predecessor-version":[{"id":32260,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/32259\/revisions\/32260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media\/32164"}],"wp:attachment":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media?parent=32259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/categories?post=32259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/tags?post=32259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}