{"id":32965,"date":"2024-01-08T10:49:39","date_gmt":"2024-01-08T13:49:39","guid":{"rendered":"https:\/\/www.muniancud.cl\/portal\/?p=32965"},"modified":"2024-01-08T10:50:16","modified_gmt":"2024-01-08T13:50:16","slug":"autoridad-comunal-visita-la-ong-chiloe-silvestre-para-conocer-en-terreno-su-labor","status":"publish","type":"post","link":"https:\/\/www.muniancud.cl\/portal\/autoridad-comunal-visita-la-ong-chiloe-silvestre-para-conocer-en-terreno-su-labor\/","title":{"rendered":"Autoridad comunal visita la ONG Chilo\u00e9 Silvestre para conocer en terreno su labor"},"content":{"rendered":"<p><strong><em>La actividad se enmarc\u00f3 en el cierre de un proyecto, el cual busc\u00f3 educar en t\u00e9rminos medioambientales a j\u00f3venes isle\u00f1os.<\/em><\/strong><\/p>\n<p>Para conocer la labor de la ONG Chilo\u00e9 Silvestre, adem\u00e1s de ser part\u00edcipes del cierre del proyecto Fondo de Protecci\u00f3n Ambiental (FPA) 2023 &#8216;Valorando la Biodiversidad Chilota para su Conservaci\u00f3n&#8217; -que permiti\u00f3 a dicha entidad realizar visitas guiadas educativas para ni\u00f1os de todo Chilo\u00e9-, se organiz\u00f3 una jornada realizada en las instalaciones de la organizaci\u00f3n, ubicadas en el sector de Nal, pen\u00ednsula de Lacuy en Ancud, con la presencia de la Alcaldesa (s) Leyla Aguayo Valenzuela y el Director de Medio Ambiente, Aseo y Ornato del municipio, Alfredo Caro.<\/p>\n<p data-reader-unique-id=\"4\">En la actividad participaron estudiantes de la Escuela Especial San Carlos y del Liceo Bicentenario, adem\u00e1s del alcalde de Quemchi, Luis Mac\u00edas.<\/p>\n<p>Al respecto, Javier Cabello, director y fundador de Chilo\u00e9 Silvestre, se\u00f1al\u00f3 que \u00abestamos muy contentos de finalizar este proyecto FPA 2023, que es educaci\u00f3n para la fauna silvestre de Chilo\u00e9, y contentos tambi\u00e9n por la visita de los alcaldes porque realmente vienen aqu\u00ed a ver la realidad, de c\u00f3mo trabajamos en educaci\u00f3n y tambi\u00e9n en rehabilitaci\u00f3n\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-32968 alignright\" src=\"https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/415697435_792939156213444_4376509260529297622_n-300x169.jpg\" alt=\"\" width=\"453\" height=\"255\" srcset=\"https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/415697435_792939156213444_4376509260529297622_n-300x169.jpg 300w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/415697435_792939156213444_4376509260529297622_n-1024x576.jpg 1024w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/415697435_792939156213444_4376509260529297622_n-768x432.jpg 768w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/415697435_792939156213444_4376509260529297622_n-1536x864.jpg 1536w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/415697435_792939156213444_4376509260529297622_n-696x392.jpg 696w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/415697435_792939156213444_4376509260529297622_n-1068x601.jpg 1068w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/415697435_792939156213444_4376509260529297622_n-747x420.jpg 747w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/415697435_792939156213444_4376509260529297622_n-1920x1080.jpg 1920w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/415697435_792939156213444_4376509260529297622_n.jpg 2048w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/>El m\u00e9dico veterinario sum\u00f3 que \u00abinauguramos el muelle de la Biodiversidad como parte de este proyecto, y la invitaci\u00f3n tambi\u00e9n es a todas las autoridades de Chilo\u00e9 a venir a Chilo\u00e9 Silvestre a conocerlo, para posteriormente poder apoyar al trabajo que hacemos aqu\u00ed, el que es para toda la provincia\u00bb.<\/p>\n<p>La alcaldesa (s) de la comuna del Pudeto, sostuvo que \u00abestamos agradecidos de poder ser parte del cierre de este proyecto que fue tan significativo, principalmente para los alumnos de los establecimientos educacionales de nuestra comuna en general, y tambi\u00e9n de otras comunas de la provincia, porque entre las cosas m\u00e1s importantes para seguir resguardando nuestra fauna silvestre, est\u00e1 la educaci\u00f3n que nosotros podamos dar a estas generaciones\u00bb.<\/p>\n<p data-reader-unique-id=\"15\">Agreg\u00f3 la abogada que \u00abreconocemos los tremendos esfuerzos que hace Chilo\u00e9 Silvestre para poder realizar este trabajo de rehabilitaci\u00f3n, de educaci\u00f3n, de conservaci\u00f3n, de investigaci\u00f3n\u00bb.<\/p>\n<p>Por su parte, el educador ambiental, Patricio C\u00f3rdova, agreg\u00f3 que \u00ablogramos venir ac\u00e1 con escuelas, a conocer el sendero, el trabajo que est\u00e1n realizando, y tambi\u00e9n como decantan este tipo de iniciativas que lo que buscan es justamente fortalecer esta dimensi\u00f3n de conocer este territorio y por lo tanto cuidarlo\u00bb.<\/p>\n<p data-reader-unique-id=\"9\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-32966 alignleft\" src=\"https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/417795166_792939306213429_5088843699865328957_n-300x169.jpg\" alt=\"\" width=\"415\" height=\"234\" srcset=\"https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/417795166_792939306213429_5088843699865328957_n-300x169.jpg 300w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/417795166_792939306213429_5088843699865328957_n-1024x576.jpg 1024w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/417795166_792939306213429_5088843699865328957_n-768x432.jpg 768w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/417795166_792939306213429_5088843699865328957_n-1536x864.jpg 1536w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/417795166_792939306213429_5088843699865328957_n-696x392.jpg 696w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/417795166_792939306213429_5088843699865328957_n-1068x601.jpg 1068w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/417795166_792939306213429_5088843699865328957_n-747x420.jpg 747w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/417795166_792939306213429_5088843699865328957_n-1920x1080.jpg 1920w, https:\/\/www.muniancud.cl\/portal\/wp-content\/uploads\/2024\/01\/417795166_792939306213429_5088843699865328957_n.jpg 2048w\" sizes=\"auto, (max-width: 415px) 100vw, 415px\" \/>Consign\u00f3 que \u00ababrazamos mont\u00f3n la perspectiva de c\u00f3mo trabajan la educaci\u00f3n ambiental que es experiencial, con los sentidos, explorativa y tambi\u00e9n que busca restaurar y cuidar\u00bb.<\/p>\n<p data-reader-unique-id=\"10\">En tanto, el alcalde de Quemchi, Luis Mac\u00edas se refiri\u00f3 al trabajo que se desarrolla en este lugar, el cual es precisamente patrocinado econ\u00f3micamente por los \u00a0municipios de Quemchi y Ancud.<\/p>\n<p data-reader-unique-id=\"11\">\u00abPrimera vez que estoy aqu\u00ed en el espacio de Chilo\u00e9 Silvestre, quiero en primer lugar agradecer la invitaci\u00f3n de poder participar en el cierre de este proyecto, y este recorrido que hemos hecho hoy que ha sido corto, pero la verdad muy intenso. Observar la variedad que hay aqu\u00ed de especies que han sido rescatadas. Contentos porque este espacio es \u00fanico en Chilo\u00e9\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La actividad se enmarc\u00f3 en el cierre de un proyecto, el cual busc\u00f3 educar en t\u00e9rminos medioambientales a j\u00f3venes isle\u00f1os. Para conocer la labor de la ONG Chilo\u00e9 Silvestre, adem\u00e1s de ser part\u00edcipes del cierre del proyecto Fondo de Protecci\u00f3n Ambiental (FPA) 2023 &#8216;Valorando la Biodiversidad Chilota para su Conservaci\u00f3n&#8217; -que permiti\u00f3 a dicha entidad [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":32967,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,4],"tags":[],"class_list":["post-32965","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medio-ambiente-aseo-y-ornato","category-sala-de-prensa"],"_links":{"self":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/32965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/comments?post=32965"}],"version-history":[{"count":2,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/32965\/revisions"}],"predecessor-version":[{"id":32970,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/32965\/revisions\/32970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media\/32967"}],"wp:attachment":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media?parent=32965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/categories?post=32965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/tags?post=32965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}