{"id":33071,"date":"2024-01-23T09:26:57","date_gmt":"2024-01-23T12:26:57","guid":{"rendered":"https:\/\/www.muniancud.cl\/portal\/?p=33071"},"modified":"2024-02-13T09:29:28","modified_gmt":"2024-02-13T12:29:28","slug":"dimao-organiza-concurso-de-fotografia","status":"publish","type":"post","link":"https:\/\/www.muniancud.cl\/portal\/dimao-organiza-concurso-de-fotografia\/","title":{"rendered":"Dimao organiza concurso de fotograf\u00eda"},"content":{"rendered":"<p class=\"p2\">La Direcci\u00f3n de Medioambiente, Aseo y Ornato (Dimao) de la Municipalidad de Ancud extendi\u00f3 hasta el viernes su convocatoria para el \u00abConcurso de fotograf\u00eda de aves de los humedales urbanos de Pudeto Bajo\u00bb, iniciativa que busca poner en valor la avifauna de estas \u00e1reas para su cuidado y conservaci\u00f3n.<\/p>\n<p class=\"p2\">Junto con ello, se indic\u00f3 que este certamen difundir\u00e1 las im\u00e1genes con prop\u00f3sitos educativos, se\u00f1al\u00e9tica del lugar, infograf\u00edas, adem\u00e1s de exposici\u00f3n de los propios humedales. Samanta Guzm\u00e1n, practicante de ingenier\u00eda en recursos humanos en dicha repartici\u00f3n consistorial, explic\u00f3 que \u00abnos encontramos generando un proyecto para la valoraci\u00f3n del circuito de humedales de Pudeto Bajo\u00bb, el que incluye este certamen.<\/p>\n<p class=\"p2\">\u00abInvitamos a todos los habitantes de la ciudad y tambi\u00e9n de los alrededores a que nos env\u00eden sus fotograf\u00edas para que puedan entrar al concurso, y logremos el objetivo de cuidar la avifauna de los humedales\u00bb, sum\u00f3.<\/p>\n<p class=\"p2\">Los detalles de la competencia est\u00e1n en las redes sociales del municipio y la Dimao. Entre los premios figuran una compostera y kit de separaci\u00f3n de RSD (residuos s\u00f3lidos domiciliarios) interior para el primer lugar; solo la primera para la segunda ubicaci\u00f3n, y solo el mencionado kit para el tercer lugar.<\/p>\n<p class=\"p2\">falta traspaso<\/p>\n<p class=\"p2\">Alfredo Caro, encargado de la direcci\u00f3n ancuditana, recalc\u00f3 que \u00abel concurso busca poner en valor el circuito de humedales de Pudeto Bajo; recordemos que es un humedal urbano protegido, el primero de la regi\u00f3n y que lamentablemente el municipio no ha podido realizar inversiones producto de que Bienes Nacionales a\u00fan no traspasa este sitio en comodato a la municipalidad, para poder realizar los cierres perimetrales y las pasarelas que tenemos proyectadas para dar protecci\u00f3n y una puesta en valor significativa en conjunto con la comunidad aleda\u00f1a\u00bb.<\/p>\n<p class=\"p2\">El profesional agreg\u00f3 que \u00abaparte del concurso nos va a servir igual para tener im\u00e1genes para generar se\u00f1al\u00e9tica y concientizaci\u00f3n del lugar, vamos a generar una encuesta con la comunidad; por lo tanto, vamos a estar en la feria, en el mercado de la plaza y tambi\u00e9n obviamente en los sectores aleda\u00f1os al humedal\u00bb.<\/p>\n<p class=\"p2\">cedida<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Direcci\u00f3n de Medioambiente, Aseo y Ornato (Dimao) de la Municipalidad de Ancud extendi\u00f3 hasta el viernes su convocatoria para el \u00abConcurso de fotograf\u00eda de aves de los humedales urbanos de Pudeto Bajo\u00bb, iniciativa que busca poner en valor la avifauna de estas \u00e1reas para su cuidado y conservaci\u00f3n. Junto con ello, se indic\u00f3 que [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":33073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[32,4],"tags":[],"class_list":["post-33071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medio-ambiente-aseo-y-ornato","category-sala-de-prensa"],"_links":{"self":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/33071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/comments?post=33071"}],"version-history":[{"count":1,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/33071\/revisions"}],"predecessor-version":[{"id":33074,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/33071\/revisions\/33074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media\/33073"}],"wp:attachment":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media?parent=33071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/categories?post=33071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/tags?post=33071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}