{"id":33754,"date":"2024-06-29T11:46:40","date_gmt":"2024-06-29T15:46:40","guid":{"rendered":"https:\/\/www.muniancud.cl\/portal\/?p=33754"},"modified":"2024-07-15T11:57:46","modified_gmt":"2024-07-15T15:57:46","slug":"inauguran-camino-por-mas-de-2-170-millones-en-ancud","status":"publish","type":"post","link":"https:\/\/www.muniancud.cl\/portal\/inauguran-camino-por-mas-de-2-170-millones-en-ancud\/","title":{"rendered":"Inauguran camino por m\u00e1s de $2.170 millones en Ancud"},"content":{"rendered":"<p data-reader-unique-id=\"3\">Una inversi\u00f3n de m\u00e1s de 2 mil millones de pesos represent\u00f3 el mejoramiento del camino Chacao-Caul\u00edn en Ancud, que ayer fue entregado oficialmente a la comunidad como parte de la presencia de la ministra de Obras P\u00fablicas, Jessica L\u00f3pez, a esta comuna chilota.<\/p>\n<p data-reader-unique-id=\"4\">Tras una d\u00e9cada de espera, seg\u00fan la Delegaci\u00f3n Presidencial Provincial, la comunidad cuenta con una mejor conectividad con esta iniciativa que represent\u00f3 la intervenci\u00f3n de 7,6 kil\u00f3metros, entre la Ruta 5 Sur y Caul\u00edn y que estuvo a cargo de la empresa Itinex.<\/p>\n<p data-reader-unique-id=\"5\">A principios del mes pasado concluyeron las obras que comenzaron el 15 de junio de 2022 y que inicialmente ten\u00edan un plazo a\u00f1o y que, posteriormente, se extendieron a 684 d\u00edas, con un monto final de $2 mil 173 millones de pesos, 50 millones m\u00e1s que el presupuesto de adjudicaci\u00f3n.<\/p>\n<p data-reader-unique-id=\"6\">El proyecto consider\u00f3 una calzada de 6,2 metros de ancho promedio con una pista por sentido. La materialidad de la capa de rodadura es de asfalto en toda su longitud; adem\u00e1s, se contempl\u00f3 mejoras de saneamiento, se\u00f1alizaci\u00f3n vial y construcci\u00f3n de paraderos.<\/p>\n<p data-reader-unique-id=\"7\">Paola S\u00e1nchez, presidenta de la Uni\u00f3n Comunal de Juntas de Vecinos Rurales de Ancud, indic\u00f3 que \u00abeste era un anhelo que se ten\u00eda de muchos a\u00f1os de mejorar el camino, nuestra ruta de Chacao a Caul\u00edn Alto y ahora lo pudimos conseguir; esto nos mejora la calidad de vida y es un tremendo logro para la comunidad\u00bb.<\/p>\n<p data-reader-unique-id=\"8\">A su vez, Carlos G\u00f3mez (indep.), alcalde de Ancud, sostuvo que \u00abnosotros estamos felices, contentos y as\u00ed se ha manifestado por cada uno de nuestros vecinos y dirigentes del sector Estero Chacao. Estamos con esta primera etapa inaugur\u00e1ndola, que es desde Chacao a Caul\u00edn y estamos, por el otro lado, con la primera etapa del camino Huicha-Pugue\u00f1\u00fan, que est\u00e1 por terminar\u00bb.<\/p>\n<p data-reader-unique-id=\"9\">El jefe comunal sum\u00f3 que \u00abest\u00e1 en proceso de adjudicaci\u00f3n una segunda etapa a Caul\u00edn, tenemos un solo pero ah\u00ed que se lo manifestamos a la ministra que es un trazado de protecci\u00f3n del borde costero para poder unirlos, que no es m\u00e1s de un kil\u00f3metro, as\u00ed es que estamos felices por eso\u00bb.<\/p>\n<p data-reader-unique-id=\"10\">Si bien lleg\u00f3 a la zona para participar de la cuarta sesi\u00f3n de la Comisi\u00f3n Asesora del Puente Chacao, la titular del MOP tambi\u00e9n form\u00f3 parte de la inauguraci\u00f3n del camino que fue financiado con recursos sectoriales.<\/p>\n<p data-reader-unique-id=\"11\">\u00abEs una gran alegr\u00eda poder estar en esta inauguraci\u00f3n, cuesta tanto hacer las obras que inaugurar este camino es muy significativo, es tambi\u00e9n una alegr\u00eda. Tenemos una cartera bien grande: el Puente Chacao, la obra m\u00e1s grande que tiene el Ministerio de Obras P\u00fablicas en su cartera; la Ruta 5 entre Chacao y Chonchi, una ruta que tiene que hacerle honor a ese gran puente que estamos construyendo\u00bb, relat\u00f3 la secretaria de Estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una inversi\u00f3n de m\u00e1s de 2 mil millones de pesos represent\u00f3 el mejoramiento del camino Chacao-Caul\u00edn en Ancud, que ayer fue entregado oficialmente a la comunidad como parte de la presencia de la ministra de Obras P\u00fablicas, Jessica L\u00f3pez, a esta comuna chilota. Tras una d\u00e9cada de espera, seg\u00fan la Delegaci\u00f3n Presidencial Provincial, la comunidad [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":33755,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,29],"tags":[],"class_list":["post-33754","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-de-prensa","category-secplan"],"_links":{"self":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/33754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/comments?post=33754"}],"version-history":[{"count":1,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/33754\/revisions"}],"predecessor-version":[{"id":33756,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/posts\/33754\/revisions\/33756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media\/33755"}],"wp:attachment":[{"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/media?parent=33754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/categories?post=33754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muniancud.cl\/portal\/wp-json\/wp\/v2\/tags?post=33754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}